{"id":14536,"date":"2026-06-11T15:52:42","date_gmt":"2026-06-11T15:52:42","guid":{"rendered":"https:\/\/bofillmir.cl\/?p=14536"},"modified":"2026-06-11T16:27:00","modified_gmt":"2026-06-11T16:27:00","slug":"alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822","status":"publish","type":"post","link":"https:\/\/bofillmir.cl\/eng\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\/","title":{"rendered":"Alerta Legal &#8211; Nuevo R\u00e9gimen Laboral de la Ley 21.822"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Ley Integral de las Personas Mayores y Promoci\u00f3n del Envejecimiento Digno, Activo y Saludable.<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"http:\/\/bofillmir.cl\/wp-content\/uploads\/2026\/06\/Nuevo-Regimen-Laboral-de-la-Ley-21.822-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of Nuevo R\u00e9gimen Laboral de la Ley 21.822.\"><\/object><a id=\"wp-block-file--media-66d1ac23-76fe-419a-8a91-5f8356dc45f7\" href=\"http:\/\/bofillmir.cl\/wp-content\/uploads\/2026\/06\/Nuevo-Regimen-Laboral-de-la-Ley-21.822-1.pdf\">Nuevo R\u00e9gimen Laboral de la Ley 21.822<\/a><a href=\"http:\/\/bofillmir.cl\/wp-content\/uploads\/2026\/06\/Nuevo-Regimen-Laboral-de-la-Ley-21.822-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-66d1ac23-76fe-419a-8a91-5f8356dc45f7\">Download<\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Ley Integral de las Personas Mayores y Promoci\u00f3n del Envejecimiento Digno, Activo y Saludable.<\/p>","protected":false},"author":2,"featured_media":13573,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-14536","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alerta-legal"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ley Integral de las Personas Mayores y Promoci\u00f3n del Envejecimiento Digno, Activo y Saludable. Nuevo R\u00e9gimen Laboral de la Ley 21.822Descarga\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"nmedina@bofillmir.cl\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/bofillmir.cl\/eng\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Bofill Mir Abogados - Santiago, Chile\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Alerta Legal \u2013 Nuevo R\u00e9gimen Laboral de la Ley 21.822 - Bofill Mir Abogados\" \/>\n\t\t<meta property=\"og:description\" content=\"Ley Integral de las Personas Mayores y Promoci\u00f3n del Envejecimiento Digno, Activo y Saludable. Nuevo R\u00e9gimen Laboral de la Ley 21.822Descarga\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/bofillmir.cl\/eng\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/bofillmir.cl\/wp-content\/uploads\/2025\/09\/inaki-del-olmo-NIJuEQw0RKg-unsplash-1.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/bofillmir.cl\/wp-content\/uploads\/2025\/09\/inaki-del-olmo-NIJuEQw0RKg-unsplash-1.webp\" \/>\n\t\t<meta property=\"og:image:width\" content=\"499\" \/>\n\t\t<meta property=\"og:image:height\" content=\"333\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-06-11T15:52:42+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-06-11T16:27:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Alerta Legal \u2013 Nuevo R\u00e9gimen Laboral de la Ley 21.822 - Bofill Mir Abogados\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ley Integral de las Personas Mayores y Promoci\u00f3n del Envejecimiento Digno, Activo y Saludable. Nuevo R\u00e9gimen Laboral de la Ley 21.822Descarga\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/bofillmir.cl\/wp-content\/uploads\/2025\/09\/inaki-del-olmo-NIJuEQw0RKg-unsplash-1.webp\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\\\/#blogposting\",\"name\":\"Alerta Legal \\u2013 Nuevo R\\u00e9gimen Laboral de la Ley 21.822 - Bofill Mir Abogados\",\"headline\":\"Alerta Legal &#8211; Nuevo R\\u00e9gimen Laboral de la Ley 21.822\",\"author\":{\"@id\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/author\\\/nmedinabofillmir-cl\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/bofillmir.cl\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/inaki-del-olmo-NIJuEQw0RKg-unsplash-1.webp\",\"width\":499,\"height\":333},\"datePublished\":\"2026-06-11T15:52:42+00:00\",\"dateModified\":\"2026-06-11T16:27:00+00:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\\\/#webpage\"},\"articleSection\":\"Alerta legal\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bofillmir.cl\\\/eng#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/bofillmir.cl\\\/eng\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/category\\\/alerta-legal\\\/#listItem\",\"name\":\"Alerta legal\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/category\\\/alerta-legal\\\/#listItem\",\"position\":2,\"name\":\"Alerta legal\",\"item\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/category\\\/alerta-legal\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\\\/#listItem\",\"name\":\"Alerta Legal &#8211; Nuevo R\\u00e9gimen Laboral de la Ley 21.822\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bofillmir.cl\\\/eng#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\\\/#listItem\",\"position\":3,\"name\":\"Alerta Legal &#8211; Nuevo R\\u00e9gimen Laboral de la Ley 21.822\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/category\\\/alerta-legal\\\/#listItem\",\"name\":\"Alerta legal\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/#organization\",\"name\":\"Boofill Mir\",\"description\":\"Santiago, Chile\",\"url\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/author\\\/nmedinabofillmir-cl\\\/#author\",\"url\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/author\\\/nmedinabofillmir-cl\\\/\",\"name\":\"nmedina@bofillmir.cl\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/74a09b1359364a63932648557809db58e7b2dc305b355121d797c4efd385feda?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"nmedina@bofillmir.cl\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\\\/#webpage\",\"url\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\\\/\",\"name\":\"Alerta Legal \\u2013 Nuevo R\\u00e9gimen Laboral de la Ley 21.822 - Bofill Mir Abogados\",\"description\":\"Ley Integral de las Personas Mayores y Promoci\\u00f3n del Envejecimiento Digno, Activo y Saludable. Nuevo R\\u00e9gimen Laboral de la Ley 21.822Descarga\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/author\\\/nmedinabofillmir-cl\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/author\\\/nmedinabofillmir-cl\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/bofillmir.cl\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/inaki-del-olmo-NIJuEQw0RKg-unsplash-1.webp\",\"@id\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\\\/#mainImage\",\"width\":499,\"height\":333},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\\\/#mainImage\"},\"datePublished\":\"2026-06-11T15:52:42+00:00\",\"dateModified\":\"2026-06-11T16:27:00+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/#website\",\"url\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/\",\"name\":\"Boofill Mir\",\"description\":\"Santiago, Chile\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/bofillmir.cl\\\/eng\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Alerta Legal \u2013 Nuevo R\u00e9gimen Laboral de la Ley 21.822 - Bofill Mir Abogados","description":"Ley Integral de las Personas Mayores y Promoci\u00f3n del Envejecimiento Digno, Activo y Saludable. Nuevo R\u00e9gimen Laboral de la Ley 21.822Descarga","canonical_url":"https:\/\/bofillmir.cl\/eng\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/bofillmir.cl\/eng\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\/#blogposting","name":"Alerta Legal \u2013 Nuevo R\u00e9gimen Laboral de la Ley 21.822 - Bofill Mir Abogados","headline":"Alerta Legal &#8211; Nuevo R\u00e9gimen Laboral de la Ley 21.822","author":{"@id":"https:\/\/bofillmir.cl\/eng\/author\/nmedinabofillmir-cl\/#author"},"publisher":{"@id":"https:\/\/bofillmir.cl\/eng\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/bofillmir.cl\/wp-content\/uploads\/2025\/09\/inaki-del-olmo-NIJuEQw0RKg-unsplash-1.webp","width":499,"height":333},"datePublished":"2026-06-11T15:52:42+00:00","dateModified":"2026-06-11T16:27:00+00:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/bofillmir.cl\/eng\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\/#webpage"},"isPartOf":{"@id":"https:\/\/bofillmir.cl\/eng\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\/#webpage"},"articleSection":"Alerta legal"},{"@type":"BreadcrumbList","@id":"https:\/\/bofillmir.cl\/eng\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/bofillmir.cl\/eng#listItem","position":1,"name":"Inicio","item":"https:\/\/bofillmir.cl\/eng","nextItem":{"@type":"ListItem","@id":"https:\/\/bofillmir.cl\/eng\/category\/alerta-legal\/#listItem","name":"Alerta legal"}},{"@type":"ListItem","@id":"https:\/\/bofillmir.cl\/eng\/category\/alerta-legal\/#listItem","position":2,"name":"Alerta legal","item":"https:\/\/bofillmir.cl\/eng\/category\/alerta-legal\/","nextItem":{"@type":"ListItem","@id":"https:\/\/bofillmir.cl\/eng\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\/#listItem","name":"Alerta Legal &#8211; Nuevo R\u00e9gimen Laboral de la Ley 21.822"},"previousItem":{"@type":"ListItem","@id":"https:\/\/bofillmir.cl\/eng#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/bofillmir.cl\/eng\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\/#listItem","position":3,"name":"Alerta Legal &#8211; Nuevo R\u00e9gimen Laboral de la Ley 21.822","previousItem":{"@type":"ListItem","@id":"https:\/\/bofillmir.cl\/eng\/category\/alerta-legal\/#listItem","name":"Alerta legal"}}]},{"@type":"Organization","@id":"https:\/\/bofillmir.cl\/eng\/#organization","name":"Boofill Mir","description":"Santiago, Chile","url":"https:\/\/bofillmir.cl\/eng\/"},{"@type":"Person","@id":"https:\/\/bofillmir.cl\/eng\/author\/nmedinabofillmir-cl\/#author","url":"https:\/\/bofillmir.cl\/eng\/author\/nmedinabofillmir-cl\/","name":"nmedina@bofillmir.cl","image":{"@type":"ImageObject","@id":"https:\/\/bofillmir.cl\/eng\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/74a09b1359364a63932648557809db58e7b2dc305b355121d797c4efd385feda?s=96&d=mm&r=g","width":96,"height":96,"caption":"nmedina@bofillmir.cl"}},{"@type":"WebPage","@id":"https:\/\/bofillmir.cl\/eng\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\/#webpage","url":"https:\/\/bofillmir.cl\/eng\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\/","name":"Alerta Legal \u2013 Nuevo R\u00e9gimen Laboral de la Ley 21.822 - Bofill Mir Abogados","description":"Ley Integral de las Personas Mayores y Promoci\u00f3n del Envejecimiento Digno, Activo y Saludable. Nuevo R\u00e9gimen Laboral de la Ley 21.822Descarga","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/bofillmir.cl\/eng\/#website"},"breadcrumb":{"@id":"https:\/\/bofillmir.cl\/eng\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\/#breadcrumblist"},"author":{"@id":"https:\/\/bofillmir.cl\/eng\/author\/nmedinabofillmir-cl\/#author"},"creator":{"@id":"https:\/\/bofillmir.cl\/eng\/author\/nmedinabofillmir-cl\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/bofillmir.cl\/wp-content\/uploads\/2025\/09\/inaki-del-olmo-NIJuEQw0RKg-unsplash-1.webp","@id":"https:\/\/bofillmir.cl\/eng\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\/#mainImage","width":499,"height":333},"primaryImageOfPage":{"@id":"https:\/\/bofillmir.cl\/eng\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\/#mainImage"},"datePublished":"2026-06-11T15:52:42+00:00","dateModified":"2026-06-11T16:27:00+00:00"},{"@type":"WebSite","@id":"https:\/\/bofillmir.cl\/eng\/#website","url":"https:\/\/bofillmir.cl\/eng\/","name":"Boofill Mir","description":"Santiago, Chile","inLanguage":"en-US","publisher":{"@id":"https:\/\/bofillmir.cl\/eng\/#organization"}}]},"og:locale":"en_US","og:site_name":"Bofill Mir Abogados - Santiago, Chile","og:type":"article","og:title":"Alerta Legal \u2013 Nuevo R\u00e9gimen Laboral de la Ley 21.822 - Bofill Mir Abogados","og:description":"Ley Integral de las Personas Mayores y Promoci\u00f3n del Envejecimiento Digno, Activo y Saludable. Nuevo R\u00e9gimen Laboral de la Ley 21.822Descarga","og:url":"https:\/\/bofillmir.cl\/eng\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\/","og:image":"https:\/\/bofillmir.cl\/wp-content\/uploads\/2025\/09\/inaki-del-olmo-NIJuEQw0RKg-unsplash-1.webp","og:image:secure_url":"https:\/\/bofillmir.cl\/wp-content\/uploads\/2025\/09\/inaki-del-olmo-NIJuEQw0RKg-unsplash-1.webp","og:image:width":499,"og:image:height":333,"article:published_time":"2026-06-11T15:52:42+00:00","article:modified_time":"2026-06-11T16:27:00+00:00","twitter:card":"summary_large_image","twitter:title":"Alerta Legal \u2013 Nuevo R\u00e9gimen Laboral de la Ley 21.822 - Bofill Mir Abogados","twitter:description":"Ley Integral de las Personas Mayores y Promoci\u00f3n del Envejecimiento Digno, Activo y Saludable. Nuevo R\u00e9gimen Laboral de la Ley 21.822Descarga","twitter:image":"https:\/\/bofillmir.cl\/wp-content\/uploads\/2025\/09\/inaki-del-olmo-NIJuEQw0RKg-unsplash-1.webp"},"aioseo_meta_data":{"post_id":"14536","title":null,"description":null,"keywords":null,"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-06-11 15:52:44","updated":"2026-08-06 15:59:37","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/bofillmir.cl\/eng\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/bofillmir.cl\/eng\/category\/alerta-legal\/\" title=\"Alerta legal\">Alerta legal<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAlerta Legal \u2013 Nuevo R\u00e9gimen Laboral de la Ley 21.822\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/bofillmir.cl\/eng"},{"label":"Alerta legal","link":"https:\/\/bofillmir.cl\/eng\/category\/alerta-legal\/"},{"label":"Alerta Legal &#8211; Nuevo R\u00e9gimen Laboral de la Ley 21.822","link":"https:\/\/bofillmir.cl\/eng\/alerta-legal-nuevo-regimen-laboral-de-la-ley-21-822\/"}],"_links":{"self":[{"href":"https:\/\/bofillmir.cl\/eng\/wp-json\/wp\/v2\/posts\/14536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bofillmir.cl\/eng\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bofillmir.cl\/eng\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bofillmir.cl\/eng\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bofillmir.cl\/eng\/wp-json\/wp\/v2\/comments?post=14536"}],"version-history":[{"count":3,"href":"https:\/\/bofillmir.cl\/eng\/wp-json\/wp\/v2\/posts\/14536\/revisions"}],"predecessor-version":[{"id":14542,"href":"https:\/\/bofillmir.cl\/eng\/wp-json\/wp\/v2\/posts\/14536\/revisions\/14542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bofillmir.cl\/eng\/wp-json\/wp\/v2\/media\/13573"}],"wp:attachment":[{"href":"https:\/\/bofillmir.cl\/eng\/wp-json\/wp\/v2\/media?parent=14536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bofillmir.cl\/eng\/wp-json\/wp\/v2\/categories?post=14536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bofillmir.cl\/eng\/wp-json\/wp\/v2\/tags?post=14536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}